{"id":22,"count":4,"description":"Instruments de protection des signaux GNSS et modules de contre-mesures : d\u00e9tecteurs de falsification en temps r\u00e9el qui recoupent les donn\u00e9es des constellations et signalent les signaux frauduleux, ainsi que des sources RF \u00e0 large bande destin\u00e9es aux tests d'interf\u00e9rences autoris\u00e9es et au d\u00e9veloppement de contre-mesures.","link":"https:\/\/navshieldglobal.com\/fr\/product-category\/signal-protection-countermeasures\/","name":"Protection des signaux et contre-mesures","slug":"mesures-de-protection-des-signaux","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/navshieldglobal.com\/fr\/wp-json\/wp\/v2\/product_cat\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/navshieldglobal.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/navshieldglobal.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/navshieldglobal.com\/fr\/wp-json\/wp\/v2\/product?product_cat=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}